{"text_format":"1","workbook":"xlsx","n_sheets":3,"sheets":["Лист1","расчет","виды"],"not_rendered":{"charts":0,"images":0,"macros":1,"external_links":1,"defined_names":8,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Лист1","index":0,"n_rows":100,"n_cols":15,"rows_kept":100,"cut":false,"hidden":false,"merged":[[0,14,1,14],[0,12,1,12],[0,13,1,13],[0,0,1,0],[0,2,1,2],[0,1,1,1],[0,3,0,5],[0,6,0,8],[0,9,0,11]]}
["ФИО полностью в род падеже","Адрес проживания","Вид налога (выбрать из списка)","Транспотрный",null,null,"Змельный",null,null,"Имущественный",null,null,"Итоговая залолженность руб","Размер госпошлины рублей","Проверка"]
[null,null,null,"налог","пеня","Период взыскания","налог","пеня","Период взыскания","налог","пеня","Период взыскания"]
["Никитина Романа Викторовича","город Южно-Сахалинск, ул. Ленина, 44,32","транспортный",10.99,7.01,2014,null,null,null,null,null,null,{"$f":"IF(C3=\"транспортный\",SUM(D3:E3),IF(C3=\"земельный\",SUM(G3:H3),IF(C3=\"имущественный\",SUM(J3:K3),IF(C3=\"транспортный-земельный\",SUM(D3:E3)+SUM(G3:H3),IF(C3=\"транспортный-имущественный\",SUM(D3:E3)+SUM(J3:K3),IF(C3=\"имущественный-земельный\",SUM(J3:K3)+SUM(G3:H3),IF(C3=\"транспортный-земельный-имущественный\",SUM(D3:E3)+SUM(J3:K3)+SUM(G3:H3),\"\")))))))","v":18},{"$f":"IF(M3=\"\",\"\",IF(M3<=20000,(IF((M3*0.04)<400,400,M3*0.04)),IF(AND(M3>=20001,M3<=100000),800+((M3-20000)*0.03),IF(AND(M3>=100001,M3<=200000),3200+((M3-100000)*0.02),IF(AND(M3>=200001,M3<=1000000),5200+((M3-200000)*0.01),IF(M3>=1000000,13200+((M3-1000000)*0.005),\"ошибка\"))))))","v":400},{"$f":"IF(AND(C3=\"транспортный\",SUM(D3:E3)>0,SUM(G3:K3)<=0),\"ok\",IF(AND(C3=\"земельный\",SUM(G3:H3)>0,SUM(D3:E3)<=0,SUM(J3:K3)<=0),\"ok\",IF(AND(C3=\"имущественный\",SUM(J3:K3)>0,SUM(D3:H3)<=0),\"ok\",IF(AND(C3=\"транспортный-земельный\",SUM(D3:H3)>0,SUM(J3:K3)<=0),\"ok\",IF(AND(C3=\"транспортный-имущественный\",SUM(D3:E3),SUM(J3:K3)>0,SUM(G3:H3)<=0),\"ok\",IF(AND(C3=\"имущественный-земельный\",SUM(G3:K3)>0,SUM(D3:E3)<=0),\"ok\",IF(AND(C3=\"транспортный-земельный-имущественный\",SUM(D3:K3)>0),\"ok\",IF(C3=\"\",\"\",\"ошибка\"))))))))","v":"ok"}]
["Сидорова Ивана Васильевича","город Южно-Сахалинск, ул. Ленина, 44,33","земельный",null,null,null,234.56,12.86,2010,null,null,null,{"$f":"IF(C4=\"транспортный\",SUM(D4:E4),IF(C4=\"земельный\",SUM(G4:H4),IF(C4=\"имущественный\",SUM(J4:K4),IF(C4=\"транспортный-земельный\",SUM(D4:E4)+SUM(G4:H4),IF(C4=\"транспортный-имущественный\",SUM(D4:E4)+SUM(J4:K4),IF(C4=\"имущественный-земельный\",SUM(J4:K4)+SUM(G4:H4),IF(C4=\"транспортный-земельный-имущественный\",SUM(D4:E4)+SUM(J4:K4)+SUM(G4:H4),\"\")))))))","v":247.42000000000002},{"$f":"IF(M4=\"\",\"\",IF(M4<=20000,(IF((M4*0.04)<400,400,M4*0.04)),IF(AND(M4>=20001,M4<=100000),800+((M4-20000)*0.03),IF(AND(M4>=100001,M4<=200000),3200+((M4-100000)*0.02),IF(AND(M4>=200001,M4<=1000000),5200+((M4-200000)*0.01),IF(M4>=1000000,13200+((M4-1000000)*0.005),\"ошибка\"))))))","v":400},{"$f":"IF(AND(C4=\"транспортный\",SUM(D4:E4)>0,SUM(G4:K4)<=0),\"ok\",IF(AND(C4=\"земельный\",SUM(G4:H4)>0,SUM(D4:E4)<=0,SUM(J4:K4)<=0),\"ok\",IF(AND(C4=\"имущественный\",SUM(J4:K4)>0,SUM(D4:H4)<=0),\"ok\",IF(AND(C4=\"транспортный-земельный\",SUM(D4:H4)>0,SUM(J4:K4)<=0),\"ok\",IF(AND(C4=\"транспортный-имущественный\",SUM(D4:E4),SUM(J4:K4)>0,SUM(G4:H4)<=0),\"ok\",IF(AND(C4=\"имущественный-земельный\",SUM(G4:K4)>0,SUM(D4:E4)<=0),\"ok\",IF(AND(C4=\"транспортный-земельный-имущественный\",SUM(D4:K4)>0),\"ok\",IF(C4=\"\",\"\",\"ошибка\"))))))))","v":"ok"}]
["Петренко Ивана Васильевича","город Корсаков, ул. Советская, 33,45","имущественный",null,null,null,null,null,null,4558.3,"425,5","2014",4558.3,400,"ok"]
["Иванова Михаила Юрьевича","город Фрунзе","транспортный-земельный",21000.55,67,2014,67.010000000000005,54.6,2013,null,null,null,21189.16,835.6748,"ok"]
["Носкова Романа Романовича","город Фрунзе","транспортный-имущественный",23154.99,5.25,2010,null,null,null,56.79,"65,58","2014",23217.030000000002,896.51090000000011,"ok"]
["Петров Семён Иванович","город Свердловск","транспортный-земельный-имущественный",1000785,56,2014,785.58,78.260000000000005,2014,6.8,"5","2014",1001711.64,13208.558199999999,"ok"]
["Сидоров Илья Романович","город Фрунзе","имущественный-земельный",null,null,null,48955.25,4555.3999999999996,2014,489.5,"4269,14",2013,54000.15,1820.0045,"ok"]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(C68=\"транспортный\",SUM(D68:E68),IF(C68=\"земельный\",SUM(G68:H68),IF(C68=\"имущественный\",SUM(J68:K68),IF(C68=\"транспортный-земельный\",SUM(D68:E68)+SUM(G68:H68),IF(C68=\"транспортный-имущественный\",SUM(D68:E68)+SUM(J68:K68),IF(C68=\"имущественный-земельный\",SUM(J68:K68)+SUM(G68:H68),IF(C68=\"транспортный-земельный-имущественный\",SUM(D68:E68)+SUM(J68:K68)+SUM(G68:H68),\"\")))))))","v":""},{"$f":"IF(M68=\"\",\"\",IF(M68<=20000,(IF((M68*0.04)<400,400,M68*0.04)),IF(AND(M68>=20001,M68<=100000),800+((M68-20000)*0.03),IF(AND(M68>=100001,M68<=200000),3200+((M68-100000)*0.02),IF(AND(M68>=200001,M68<=1000000),5200+((M68-200000)*0.01),IF(M68>=1000000,13200+((M68-1000000)*0.005),\"ошибка\"))))))","v":""},{"$f":"IF(AND(C68=\"транспортный\",SUM(D68:E68)>0,SUM(G68:K68)<=0),\"ok\",IF(AND(C68=\"земельный\",SUM(G68:H68)>0,SUM(D68:E68)<=0,SUM(J68:K68)<=0),\"ok\",IF(AND(C68=\"имущественный\",SUM(J68:K68)>0,SUM(D68:H68)<=0),\"ok\",IF(AND(C68=\"транспортный-земельный\",SUM(D68:H68)>0,SUM(J68:K68)<=0),\"ok\",IF(AND(C68=\"транспортный-имущественный\",SUM(D68:E68),SUM(J68:K68)>0,SUM(G68:H68)<=0),\"ok\",IF(AND(C68=\"имущественный-земельный\",SUM(G68:K68)>0,SUM(D68:E68)<=0),\"ok\",IF(AND(C68=\"транспортный-земельный-имущественный\",SUM(D68:K68)>0),\"ok\",IF(C68=\"\",\"\",\"ошибка\"))))))))","v":""}]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]
[null,null,null,null,null,null,null,null,null,null,null,null,"","",""]

{"sheet":"расчет","index":1,"n_rows":131,"n_cols":24,"rows_kept":131,"cut":false,"hidden":false,"merged":[]}
["{ФИО полностью в род падеже}","{Адрес проживания}","{Вид налога}","{транспортный налог руб}","{транспортный налог коп}","{транспортный пеня руб}","{транспортный пеня коп}","{Период взыскания транспортного налога}","{земельный налог руб}","{земельный налог коп}","{земельный пеня руб}","{земельный пеня коп}","{Период взыскания земельного налога}","{имущественный налог руб}","{имущественный налог коп}","{имущественный пеня руб}","{имущественный пеня коп}","{Период взыскания имущественного налога}","{Итоговая залолженность руб}","{Итоговая залолженность коп.}","{Размер госпошлины рублей}","{Размер госпошлины копеек}","{Дата полностью}","проверка"]
[{"$f":"IF(Лист1!A3=\"\",\"\",Лист1!A3)","v":"Никитина Романа Викторовича"},{"$f":"IF(Лист1!B3=\"\",\"\",Лист1!B3)","v":"город Южно-Сахалинск, ул. Ленина, 44,32"},{"$f":"IF(Лист1!C3=\"\",\"\",Лист1!C3)","v":"транспортный"},{"$f":"IF(Лист1!D3>0,INT(Лист1!D3),\"\")","v":10},{"$f":"IF(D2<>\"\",(Лист1!D3-D2)*100,\"\")","v":99.000000000000028},{"$f":"IF(Лист1!E3>0,INT(Лист1!E3),\"\")","v":7},{"$f":"IF(F2<>\"\",(Лист1!E3-F2)*100,\"\")","v":0.99999999999997868},{"$f":"IF(Лист1!F3=\"\",\"\",Лист1!F3)","v":2014},{"$f":"IF(Лист1!G3>0,INT(Лист1!G3),\"\")","v":""},{"$f":"IF(I2<>\"\",(Лист1!G3-I2)*100,\"\")","v":""},{"$f":"IF(Лист1!H3>0,INT(Лист1!H3),\"\")","v":""},{"$f":"IF(K2<>\"\",(Лист1!H3-K2)*100,\"\")","v":""},{"$f":"IF(Лист1!I3=\"\",\"\",Лист1!I3)","v":""},{"$f":"IF(Лист1!J3>0,INT(Лист1!J3),\"\")","v":""},{"$f":"IF(N2<>\"\",(Лист1!J3-N2)*100,\"\")","v":""},{"$f":"IF(Лист1!K3>0,INT(Лист1!K3),\"\")","v":""},{"$f":"IF(P2<>\"\",(Лист1!K3-P2)*100,\"\")","v":""},{"$f":"IF(Лист1!L3=\"\",\"\",Лист1!L3)","v":""},{"$f":"IF(Лист1!M3=\"\",\"\",INT(Лист1!M3))","v":18},{"$f":"IF(S2<>\"\",(Лист1!M3-S2)*100,\"\")","v":0},779,"11","2014-12-13",{"$f":"IF(AND(расчет!C2=\"транспортный\",SUM(I2:Q2)=0,SUM(F2:G2)>0),\"верно\",IF(AND(расчет!C2=\"имущественный\",SUM(F2:L2)=0,SUM(N2:Q2)>0),\"верно\",IF(AND(расчет!C2=\"земельный\",SUM(N2:Q2)+SUM(F2:G2)=0,SUM(I2:L2)>0),\"верно\",IF(AND(расчет!C2=\"имущественный-земельный\",SUM(F2:G2)=0,SUM(I2:Q2)>0),\"верно\",IF(AND(расчет!C2=\"транспортный-земельный\",SUM(N2:Q2)=0,SUM(F2:L2)>0),\"верно\",IF(AND(расчет!C2=\"транспортный-имущественный\",SUM(I2:L2)=0,(SUM(F2:G2)+SUM(N2:Q2))>0),\"верно\",IF(AND(расчет!C2=\"транспортный-земельный-имущественный\",SUM(N2:Q2)>0),\"верно\",IF(AND(расчет!C2=\"\",SUM(N2:Q2)=0),\"\",\"ОШИБКА!\"))))))))","v":"верно"}]
[{"$f":"IF(Лист1!A4=\"\",\"\",Лист1!A4)","v":"Сидорова Ивана Васильевича"},{"$f":"IF(Лист1!B4=\"\",\"\",Лист1!B4)","v":"город Южно-Сахалинск, ул. Ленина, 44,33"},{"$f":"IF(Лист1!C4=\"\",\"\",Лист1!C4)","v":"земельный"},{"$f":"IF(Лист1!D4>0,INT(Лист1!D4),\"\")","v":""},{"$f":"IF(D3<>\"\",(Лист1!D4-D3)*100,\"\")","v":""},{"$f":"IF(Лист1!E4>0,INT(Лист1!E4),\"\")","v":""},{"$f":"IF(F3<>\"\",(Лист1!E4-F3)*100,\"\")","v":""},{"$f":"IF(Лист1!F4=\"\",\"\",Лист1!F4)","v":""},{"$f":"IF(Лист1!G4>0,INT(Лист1!G4),\"\")","v":234},{"$f":"IF(I3<>\"\",(Лист1!G4-I3)*100,\"\")","v":56.000000000000227},{"$f":"IF(Лист1!H4>0,INT(Лист1!H4),\"\")","v":12},{"$f":"IF(K3<>\"\",(Лист1!H4-K3)*100,\"\")","v":85.999999999999943},{"$f":"IF(Лист1!I4=\"\",\"\",Лист1!I4)","v":2010},{"$f":"IF(Лист1!J4>0,INT(Лист1!J4),\"\")","v":""},{"$f":"IF(N3<>\"\",(Лист1!J4-N3)*100,\"\")","v":""},{"$f":"IF(Лист1!K4>0,INT(Лист1!K4),\"\")","v":""},{"$f":"IF(P3<>\"\",(Лист1!K4-P3)*100,\"\")","v":""},{"$f":"IF(Лист1!L4=\"\",\"\",Лист1!L4)","v":""},{"$f":"IF(Лист1!M4=\"\",\"\",INT(Лист1!M4))","v":247},{"$f":"IF(S3<>\"\",(Лист1!M4-S3)*100,\"\")","v":42.000000000001592},781,0,"2014-12-13",{"$f":"IF(AND(расчет!C3=\"транспортный\",SUM(I3:Q3)=0,SUM(F3:G3)>0),\"верно\",IF(AND(расчет!C3=\"имущественный\",SUM(F3:L3)=0,SUM(N3:Q3)>0),\"верно\",IF(AND(расчет!C3=\"земельный\",SUM(N3:Q3)+SUM(F3:G3)=0,SUM(I3:L3)>0),\"верно\",IF(AND(расчет!C3=\"имущественный-земельный\",SUM(F3:G3)=0,SUM(I3:Q3)>0),\"верно\",IF(AND(расчет!C3=\"транспортный-земельный\",SUM(N3:Q3)=0,SUM(F3:L3)>0),\"верно\",IF(AND(расчет!C3=\"транспортный-имущественный\",SUM(I3:L3)=0,(SUM(F3:G3)+SUM(N3:Q3))>0),\"верно\",IF(AND(расчет!C3=\"транспортный-земельный-имущественный\",SUM(N3:Q3)>0),\"верно\",IF(AND(расчет!C3=\"\",SUM(N3:Q3)=0),\"\",\"ОШИБКА!\"))))))))","v":"верно"}]
[{"$f":"IF(Лист1!A5=\"\",\"\",Лист1!A5)","v":"Петренко Ивана Васильевича"},{"$f":"IF(Лист1!B5=\"\",\"\",Лист1!B5)","v":"город Корсаков, ул. Советская, 33,45"},{"$f":"IF(Лист1!C5=\"\",\"\",Лист1!C5)","v":"имущественный"},{"$f":"IF(Лист1!D5>0,INT(Лист1!D5),\"\")","v":""},{"$f":"IF(D4<>\"\",(Лист1!D5-D4)*100,\"\")","v":""},{"$f":"IF(Лист1!E5>0,INT(Лист1!E5),\"\")","v":""},{"$f":"IF(F4<>\"\",(Лист1!E5-F4)*100,\"\")","v":""},{"$f":"IF(Лист1!F5=\"\",\"\",Лист1!F5)","v":""},{"$f":"IF(Лист1!G5>0,INT(Лист1!G5),\"\")","v":""},{"$f":"IF(I4<>\"\",(Лист1!G5-I4)*100,\"\")","v":""},{"$f":"IF(Лист1!H5>0,INT(Лист1!H5),\"\")","v":""},{"$f":"IF(K4<>\"\",(Лист1!H5-K4)*100,\"\")","v":""},{"$f":"IF(Лист1!I5=\"\",\"\",Лист1!I5)","v":""},{"$f":"IF(Лист1!J5>0,INT(Лист1!J5),\"\")","v":4558},{"$f":"IF(N4<>\"\",(Лист1!J5-N4)*100,\"\")","v":30.00000000001819},{"$f":"IF(Лист1!K5>0,INT(Лист1!K5),\"\")","v":425},{"$f":"IF(P4<>\"\",(Лист1!K5-P4)*100,\"\")","v":50},{"$f":"IF(Лист1!L5=\"\",\"\",Лист1!L5)","v":"2014"},{"$f":"IF(Лист1!M5=\"\",\"\",INT(Лист1!M5))","v":4558},{"$f":"IF(S4<>\"\",(Лист1!M5-S4)*100,\"\")","v":30.00000000001819},781,12,"2014-12-13",{"$f":"IF(AND(расчет!C4=\"транспортный\",SUM(I4:Q4)=0,SUM(F4:G4)>0),\"верно\",IF(AND(расчет!C4=\"имущественный\",SUM(F4:L4)=0,SUM(N4:Q4)>0),\"верно\",IF(AND(расчет!C4=\"земельный\",SUM(N4:Q4)+SUM(F4:G4)=0,SUM(I4:L4)>0),\"верно\",IF(AND(расчет!C4=\"имущественный-земельный\",SUM(F4:G4)=0,SUM(I4:Q4)>0),\"верно\",IF(AND(расчет!C4=\"транспортный-земельный\",SUM(N4:Q4)=0,SUM(F4:L4)>0),\"верно\",IF(AND(расчет!C4=\"транспортный-имущественный\",SUM(I4:L4)=0,(SUM(F4:G4)+SUM(N4:Q4))>0),\"верно\",IF(AND(расчет!C4=\"транспортный-земельный-имущественный\",SUM(N4:Q4)>0),\"верно\",IF(AND(расчет!C4=\"\",SUM(N4:Q4)=0),\"\",\"ОШИБКА!\"))))))))","v":"верно"}]
[{"$f":"IF(Лист1!A6=\"\",\"\",Лист1!A6)","v":"Иванова Михаила Юрьевича"},{"$f":"IF(Лист1!B6=\"\",\"\",Лист1!B6)","v":"город Фрунзе"},{"$f":"IF(Лист1!C6=\"\",\"\",Лист1!C6)","v":"транспортный-земельный"},{"$f":"IF(Лист1!D6>0,INT(Лист1!D6),\"\")","v":21000},{"$f":"IF(D5<>\"\",(Лист1!D6-D5)*100,\"\")","v":54.99999999992724},{"$f":"IF(Лист1!E6>0,INT(Лист1!E6),\"\")","v":67},{"$f":"IF(F5<>\"\",(Лист1!E6-F5)*100,\"\")","v":0},{"$f":"IF(Лист1!F6=\"\",\"\",Лист1!F6)","v":2014},{"$f":"IF(Лист1!G6>0,INT(Лист1!G6),\"\")","v":67},{"$f":"IF(I5<>\"\",(Лист1!G6-I5)*100,\"\")","v":1.0000000000005116},{"$f":"IF(Лист1!H6>0,INT(Лист1!H6),\"\")","v":54},{"$f":"IF(K5<>\"\",(Лист1!H6-K5)*100,\"\")","v":60.000000000000142},{"$f":"IF(Лист1!I6=\"\",\"\",Лист1!I6)","v":2013},{"$f":"IF(Лист1!J6>0,INT(Лист1!J6),\"\")","v":""},{"$f":"IF(N5<>\"\",(Лист1!J6-N5)*100,\"\")","v":""},{"$f":"IF(Лист1!K6>0,INT(Лист1!K6),\"\")","v":""},{"$f":"IF(P5<>\"\",(Лист1!K6-P5)*100,\"\")","v":""},{"$f":"IF(Лист1!L6=\"\",\"\",Лист1!L6)","v":""},{"$f":"IF(Лист1!M6=\"\",\"\",INT(Лист1!M6))","v":21189},{"$f":"IF(S5<>\"\",(Лист1!M6-S5)*100,\"\")","v":15.999999999985448},781,10,"2014-12-13",{"$f":"IF(AND(расчет!C5=\"транспортный\",SUM(I5:Q5)=0,SUM(F5:G5)>0),\"верно\",IF(AND(расчет!C5=\"имущественный\",SUM(F5:L5)=0,SUM(N5:Q5)>0),\"верно\",IF(AND(расчет!C5=\"земельный\",SUM(N5:Q5)+SUM(F5:G5)=0,SUM(I5:L5)>0),\"верно\",IF(AND(расчет!C5=\"имущественный-земельный\",SUM(F5:G5)=0,SUM(I5:Q5)>0),\"верно\",IF(AND(расчет!C5=\"транспортный-земельный\",SUM(N5:Q5)=0,SUM(F5:L5)>0),\"верно\",IF(AND(расчет!C5=\"транспортный-имущественный\",SUM(I5:L5)=0,(SUM(F5:G5)+SUM(N5:Q5))>0),\"верно\",IF(AND(расчет!C5=\"транспортный-земельный-имущественный\",SUM(N5:Q5)>0),\"верно\",IF(AND(расчет!C5=\"\",SUM(N5:Q5)=0),\"\",\"ОШИБКА!\"))))))))","v":"верно"}]
[{"$f":"IF(Лист1!A7=\"\",\"\",Лист1!A7)","v":"Носкова Романа Романовича"},{"$f":"IF(Лист1!B7=\"\",\"\",Лист1!B7)","v":"город Фрунзе"},{"$f":"IF(Лист1!C7=\"\",\"\",Лист1!C7)","v":"транспортный-имущественный"},{"$f":"IF(Лист1!D7>0,INT(Лист1!D7),\"\")","v":23154},{"$f":"IF(D6<>\"\",(Лист1!D7-D6)*100,\"\")","v":99.000000000160071},{"$f":"IF(Лист1!E7>0,INT(Лист1!E7),\"\")","v":5},{"$f":"IF(F6<>\"\",(Лист1!E7-F6)*100,\"\")","v":25},{"$f":"IF(Лист1!F7=\"\",\"\",Лист1!F7)","v":2010},{"$f":"IF(Лист1!G7>0,INT(Лист1!G7),\"\")","v":""},{"$f":"IF(I6<>\"\",(Лист1!G7-I6)*100,\"\")","v":""},{"$f":"IF(Лист1!H7>0,INT(Лист1!H7),\"\")","v":""},{"$f":"IF(K6<>\"\",(Лист1!H7-K6)*100,\"\")","v":""},{"$f":"IF(Лист1!I7=\"\",\"\",Лист1!I7)","v":""},{"$f":"IF(Лист1!J7>0,INT(Лист1!J7),\"\")","v":56},{"$f":"IF(N6<>\"\",(Лист1!J7-N6)*100,\"\")","v":78.999999999999915},{"$f":"IF(Лист1!K7>0,INT(Лист1!K7),\"\")","v":65},{"$f":"IF(P6<>\"\",(Лист1!K7-P6)*100,\"\")","v":57.999999999999829},{"$f":"IF(Лист1!L7=\"\",\"\",Лист1!L7)","v":"2014"},{"$f":"IF(Лист1!M7=\"\",\"\",INT(Лист1!M7))","v":23217},{"$f":"IF(S6<>\"\",(Лист1!M7-S6)*100,\"\")","v":3.0000000002473826},781,15,"2014-12-13",{"$f":"IF(AND(расчет!C6=\"транспортный\",SUM(I6:Q6)=0,SUM(F6:G6)>0),\"верно\",IF(AND(расчет!C6=\"имущественный\",SUM(F6:L6)=0,SUM(N6:Q6)>0),\"верно\",IF(AND(расчет!C6=\"земельный\",SUM(N6:Q6)+SUM(F6:G6)=0,SUM(I6:L6)>0),\"верно\",IF(AND(расчет!C6=\"имущественный-земельный\",SUM(F6:G6)=0,SUM(I6:Q6)>0),\"верно\",IF(AND(расчет!C6=\"транспортный-земельный\",SUM(N6:Q6)=0,SUM(F6:L6)>0),\"верно\",IF(AND(расчет!C6=\"транспортный-имущественный\",SUM(I6:L6)=0,(SUM(F6:G6)+SUM(N6:Q6))>0),\"верно\",IF(AND(расчет!C6=\"транспортный-земельный-имущественный\",SUM(N6:Q6)>0),\"верно\",IF(AND(расчет!C6=\"\",SUM(N6:Q6)=0),\"\",\"ОШИБКА!\"))))))))","v":"верно"}]
[{"$f":"IF(Лист1!A8=\"\",\"\",Лист1!A8)","v":"Петров Семён Иванович"},{"$f":"IF(Лист1!B8=\"\",\"\",Лист1!B8)","v":"город Свердловск"},{"$f":"IF(Лист1!C8=\"\",\"\",Лист1!C8)","v":"транспортный-земельный-имущественный"},{"$f":"IF(Лист1!D8>0,INT(Лист1!D8),\"\")","v":1000785},{"$f":"IF(D7<>\"\",(Лист1!D8-D7)*100,\"\")","v":0},{"$f":"IF(Лист1!E8>0,INT(Лист1!E8),\"\")","v":56},{"$f":"IF(F7<>\"\",(Лист1!E8-F7)*100,\"\")","v":0},{"$f":"IF(Лист1!F8=\"\",\"\",Лист1!F8)","v":2014},{"$f":"IF(Лист1!G8>0,INT(Лист1!G8),\"\")","v":785},{"$f":"IF(I7<>\"\",(Лист1!G8-I7)*100,\"\")","v":58.000000000004093},{"$f":"IF(Лист1!H8>0,INT(Лист1!H8),\"\")","v":78},{"$f":"IF(K7<>\"\",(Лист1!H8-K7)*100,\"\")","v":26.000000000000512},{"$f":"IF(Лист1!I8=\"\",\"\",Лист1!I8)","v":2014},{"$f":"IF(Лист1!J8>0,INT(Лист1!J8),\"\")","v":6},{"$f":"IF(N7<>\"\",(Лист1!J8-N7)*100,\"\")","v":79.999999999999986},{"$f":"IF(Лист1!K8>0,INT(Лист1!K8),\"\")","v":5},{"$f":"IF(P7<>\"\",(Лист1!K8-P7)*100,\"\")","v":0},{"$f":"IF(Лист1!L8=\"\",\"\",Лист1!L8)","v":"2014"},{"$f":"IF(Лист1!M8=\"\",\"\",INT(Лист1!M8))","v":1001711},{"$f":"IF(S7<>\"\",(Лист1!M8-S7)*100,\"\")","v":64.000000001396984},43,"43","2014-12-14",{"$f":"IF(AND(расчет!C7=\"транспортный\",SUM(I7:Q7)=0,SUM(F7:G7)>0),\"верно\",IF(AND(расчет!C7=\"имущественный\",SUM(F7:L7)=0,SUM(N7:Q7)>0),\"верно\",IF(AND(расчет!C7=\"земельный\",SUM(N7:Q7)+SUM(F7:G7)=0,SUM(I7:L7)>0),\"верно\",IF(AND(расчет!C7=\"имущественный-земельный\",SUM(F7:G7)=0,SUM(I7:Q7)>0),\"верно\",IF(AND(расчет!C7=\"транспортный-земельный\",SUM(N7:Q7)=0,SUM(F7:L7)>0),\"верно\",IF(AND(расчет!C7=\"транспортный-имущественный\",SUM(I7:L7)=0,(SUM(F7:G7)+SUM(N7:Q7))>0),\"верно\",IF(AND(расчет!C7=\"транспортный-земельный-имущественный\",SUM(N7:Q7)>0),\"верно\",IF(AND(расчет!C7=\"\",SUM(N7:Q7)=0),\"\",\"ОШИБКА!\"))))))))","v":"верно"}]
[{"$f":"IF(Лист1!A9=\"\",\"\",Лист1!A9)","v":"Сидоров Илья Романович"},{"$f":"IF(Лист1!B9=\"\",\"\",Лист1!B9)","v":"город Фрунзе"},{"$f":"IF(Лист1!C9=\"\",\"\",Лист1!C9)","v":"имущественный-земельный"},{"$f":"IF(Лист1!D9>0,INT(Лист1!D9),\"\")","v":""},{"$f":"IF(D8<>\"\",(Лист1!D9-D8)*100,\"\")","v":""},{"$f":"IF(Лист1!E9>0,INT(Лист1!E9),\"\")","v":""},{"$f":"IF(F8<>\"\",(Лист1!E9-F8)*100,\"\")","v":""},{"$f":"IF(Лист1!F9=\"\",\"\",Лист1!F9)","v":""},{"$f":"IF(Лист1!G9>0,INT(Лист1!G9),\"\")","v":48955},{"$f":"IF(I8<>\"\",(Лист1!G9-I8)*100,\"\")","v":25},{"$f":"IF(Лист1!H9>0,INT(Лист1!H9),\"\")","v":4555},{"$f":"IF(K8<>\"\",(Лист1!H9-K8)*100,\"\")","v":39.99999999996362},{"$f":"IF(Лист1!I9=\"\",\"\",Лист1!I9)","v":2014},{"$f":"IF(Лист1!J9>0,INT(Лист1!J9),\"\")","v":489},{"$f":"IF(N8<>\"\",(Лист1!J9-N8)*100,\"\")","v":50},{"$f":"IF(Лист1!K9>0,INT(Лист1!K9),\"\")","v":4269},{"$f":"IF(P8<>\"\",(Лист1!K9-P8)*100,\"\")","v":14.000000000032742},{"$f":"IF(Лист1!L9=\"\",\"\",Лист1!L9)","v":2013},{"$f":"IF(Лист1!M9=\"\",\"\",INT(Лист1!M9))","v":54000},{"$f":"IF(S8<>\"\",(Лист1!M9-S8)*100,\"\")","v":15.000000000145519},43,"44","2014-12-15",{"$f":"IF(AND(расчет!C8=\"транспортный\",SUM(I8:Q8)=0,SUM(F8:G8)>0),\"верно\",IF(AND(расчет!C8=\"имущественный\",SUM(F8:L8)=0,SUM(N8:Q8)>0),\"верно\",IF(AND(расчет!C8=\"земельный\",SUM(N8:Q8)+SUM(F8:G8)=0,SUM(I8:L8)>0),\"верно\",IF(AND(расчет!C8=\"имущественный-земельный\",SUM(F8:G8)=0,SUM(I8:Q8)>0),\"верно\",IF(AND(расчет!C8=\"транспортный-земельный\",SUM(N8:Q8)=0,SUM(F8:L8)>0),\"верно\",IF(AND(расчет!C8=\"транспортный-имущественный\",SUM(I8:L8)=0,(SUM(F8:G8)+SUM(N8:Q8))>0),\"верно\",IF(AND(расчет!C8=\"транспортный-земельный-имущественный\",SUM(N8:Q8)>0),\"верно\",IF(AND(расчет!C8=\"\",SUM(N8:Q8)=0),\"\",\"ОШИБКА!\"))))))))","v":"верно"}]
[{"$f":"IF(Лист1!A10=\"\",\"\",Лист1!A10)","v":""},null,null,null,null,null,null,{"$f":"IF(Лист1!F10=\"\",\"\",Лист1!F10)","v":""},null,null,null,null,{"$f":"IF(Лист1!I10=\"\",\"\",Лист1!I10)","v":""},null,null,null,null,{"$f":"IF(Лист1!L10=\"\",\"\",Лист1!L10)","v":""}]
[{"$f":"IF(Лист1!A11=\"\",\"\",Лист1!A11)","v":""},null,null,null,null,null,null,{"$f":"IF(Лист1!F11=\"\",\"\",Лист1!F11)","v":""},null,null,null,null,{"$f":"IF(Лист1!I11=\"\",\"\",Лист1!I11)","v":""},null,null,null,null,{"$f":"IF(Лист1!L11=\"\",\"\",Лист1!L11)","v":""}]
[{"$f":"IF(Лист1!A12=\"\",\"\",Лист1!A12)","v":""},null,null,null,null,null,null,{"$f":"IF(Лист1!F12=\"\",\"\",Лист1!F12)","v":""},null,null,null,null,{"$f":"IF(Лист1!I12=\"\",\"\",Лист1!I12)","v":""},null,null,null,null,{"$f":"IF(Лист1!L12=\"\",\"\",Лист1!L12)","v":""}]
[{"$f":"IF(Лист1!A13=\"\",\"\",Лист1!A13)","v":""},null,null,null,null,null,null,{"$f":"IF(Лист1!F13=\"\",\"\",Лист1!F13)","v":""},null,null,null,null,{"$f":"IF(Лист1!I13=\"\",\"\",Лист1!I13)","v":""},null,null,null,null,{"$f":"IF(Лист1!L13=\"\",\"\",Лист1!L13)","v":""}]
[{"$f":"IF(Лист1!A14=\"\",\"\",Лист1!A14)","v":""},null,null,null,null,null,null,{"$f":"IF(Лист1!F14=\"\",\"\",Лист1!F14)","v":""},null,null,null,null,{"$f":"IF(Лист1!I14=\"\",\"\",Лист1!I14)","v":""},null,null,null,null,{"$f":"IF(Лист1!L14=\"\",\"\",Лист1!L14)","v":""}]
[{"$f":"IF(Лист1!A15=\"\",\"\",Лист1!A15)","v":""},null,null,null,null,null,null,{"$f":"IF(Лист1!F15=\"\",\"\",Лист1!F15)","v":""},null,null,null,null,{"$f":"IF(Лист1!I15=\"\",\"\",Лист1!I15)","v":""},null,null,null,null,{"$f":"IF(Лист1!L15=\"\",\"\",Лист1!L15)","v":""}]
[{"$f":"IF(Лист1!A16=\"\",\"\",Лист1!A16)","v":""},null,null,null,null,null,null,{"$f":"IF(Лист1!F16=\"\",\"\",Лист1!F16)","v":""},null,null,null,null,{"$f":"IF(Лист1!I16=\"\",\"\",Лист1!I16)","v":""},null,null,null,null,{"$f":"IF(Лист1!L16=\"\",\"\",Лист1!L16)","v":""}]
[{"$f":"IF(Лист1!A17=\"\",\"\",Лист1!A17)","v":""},null,null,null,null,null,null,{"$f":"IF(Лист1!F17=\"\",\"\",Лист1!F17)","v":""},null,null,null,null,{"$f":"IF(Лист1!I17=\"\",\"\",Лист1!I17)","v":""},null,null,null,null,{"$f":"IF(Лист1!L17=\"\",\"\",Лист1!L17)","v":""}]
[{"$f":"IF(Лист1!A18=\"\",\"\",Лист1!A18)","v":""},null,null,null,null,null,null,{"$f":"IF(Лист1!F18=\"\",\"\",Лист1!F18)","v":""},null,null,null,null,{"$f":"IF(Лист1!I18=\"\",\"\",Лист1!I18)","v":""},null,null,null,null,{"$f":"IF(Лист1!L18=\"\",\"\",Лист1!L18)","v":""}]
[{"$f":"IF(Лист1!A19=\"\",\"\",Лист1!A19)","v":""},null,null,null,null,null,null,{"$f":"IF(Лист1!F19=\"\",\"\",Лист1!F19)","v":""},null,null,null,null,{"$f":"IF(Лист1!I19=\"\",\"\",Лист1!I19)","v":""},null,null,null,null,{"$f":"IF(Лист1!L19=\"\",\"\",Лист1!L19)","v":""}]
[{"$f":"IF(Лист1!A20=\"\",\"\",Лист1!A20)","v":""},null,null,null,null,null,null,{"$f":"IF(Лист1!F20=\"\",\"\",Лист1!F20)","v":""},null,null,null,null,{"$f":"IF(Лист1!I20=\"\",\"\",Лист1!I20)","v":""},null,null,null,null,{"$f":"IF(Лист1!L20=\"\",\"\",Лист1!L20)","v":""}]
[{"$f":"IF(Лист1!A21=\"\",\"\",Лист1!A21)","v":""},null,null,null,null,null,null,{"$f":"IF(Лист1!F21=\"\",\"\",Лист1!F21)","v":""},null,null,null,null,{"$f":"IF(Лист1!I21=\"\",\"\",Лист1!I21)","v":""},null,null,null,null,{"$f":"IF(Лист1!L21=\"\",\"\",Лист1!L21)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F22=\"\",\"\",Лист1!F22)","v":""},null,null,null,null,{"$f":"IF(Лист1!I22=\"\",\"\",Лист1!I22)","v":""},null,null,null,null,{"$f":"IF(Лист1!L22=\"\",\"\",Лист1!L22)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F23=\"\",\"\",Лист1!F23)","v":""},null,null,null,null,{"$f":"IF(Лист1!I23=\"\",\"\",Лист1!I23)","v":""},null,null,null,null,{"$f":"IF(Лист1!L23=\"\",\"\",Лист1!L23)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F24=\"\",\"\",Лист1!F24)","v":""},null,null,null,null,{"$f":"IF(Лист1!I24=\"\",\"\",Лист1!I24)","v":""},null,null,null,null,{"$f":"IF(Лист1!L24=\"\",\"\",Лист1!L24)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F25=\"\",\"\",Лист1!F25)","v":""},null,null,null,null,{"$f":"IF(Лист1!I25=\"\",\"\",Лист1!I25)","v":""},null,null,null,null,{"$f":"IF(Лист1!L25=\"\",\"\",Лист1!L25)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F26=\"\",\"\",Лист1!F26)","v":""},null,null,null,null,{"$f":"IF(Лист1!I26=\"\",\"\",Лист1!I26)","v":""},null,null,null,null,{"$f":"IF(Лист1!L26=\"\",\"\",Лист1!L26)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F27=\"\",\"\",Лист1!F27)","v":""},null,null,null,null,{"$f":"IF(Лист1!I27=\"\",\"\",Лист1!I27)","v":""},null,null,null,null,{"$f":"IF(Лист1!L27=\"\",\"\",Лист1!L27)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F28=\"\",\"\",Лист1!F28)","v":""},null,null,null,null,{"$f":"IF(Лист1!I28=\"\",\"\",Лист1!I28)","v":""},null,null,null,null,{"$f":"IF(Лист1!L28=\"\",\"\",Лист1!L28)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F29=\"\",\"\",Лист1!F29)","v":""},null,null,null,null,{"$f":"IF(Лист1!I29=\"\",\"\",Лист1!I29)","v":""},null,null,null,null,{"$f":"IF(Лист1!L29=\"\",\"\",Лист1!L29)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F30=\"\",\"\",Лист1!F30)","v":""},null,null,null,null,{"$f":"IF(Лист1!I30=\"\",\"\",Лист1!I30)","v":""},null,null,null,null,{"$f":"IF(Лист1!L30=\"\",\"\",Лист1!L30)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F31=\"\",\"\",Лист1!F31)","v":""},null,null,null,null,{"$f":"IF(Лист1!I31=\"\",\"\",Лист1!I31)","v":""},null,null,null,null,{"$f":"IF(Лист1!L31=\"\",\"\",Лист1!L31)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F32=\"\",\"\",Лист1!F32)","v":""},null,null,null,null,{"$f":"IF(Лист1!I32=\"\",\"\",Лист1!I32)","v":""},null,null,null,null,{"$f":"IF(Лист1!L32=\"\",\"\",Лист1!L32)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F33=\"\",\"\",Лист1!F33)","v":""},null,null,null,null,{"$f":"IF(Лист1!I33=\"\",\"\",Лист1!I33)","v":""},null,null,null,null,{"$f":"IF(Лист1!L33=\"\",\"\",Лист1!L33)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F34=\"\",\"\",Лист1!F34)","v":""},null,null,null,null,{"$f":"IF(Лист1!I34=\"\",\"\",Лист1!I34)","v":""},null,null,null,null,{"$f":"IF(Лист1!L34=\"\",\"\",Лист1!L34)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F35=\"\",\"\",Лист1!F35)","v":""},null,null,null,null,{"$f":"IF(Лист1!I35=\"\",\"\",Лист1!I35)","v":""},null,null,null,null,{"$f":"IF(Лист1!L35=\"\",\"\",Лист1!L35)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F36=\"\",\"\",Лист1!F36)","v":""},null,null,null,null,{"$f":"IF(Лист1!I36=\"\",\"\",Лист1!I36)","v":""},null,null,null,null,{"$f":"IF(Лист1!L36=\"\",\"\",Лист1!L36)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F37=\"\",\"\",Лист1!F37)","v":""},null,null,null,null,{"$f":"IF(Лист1!I37=\"\",\"\",Лист1!I37)","v":""},null,null,null,null,{"$f":"IF(Лист1!L37=\"\",\"\",Лист1!L37)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F38=\"\",\"\",Лист1!F38)","v":""},null,null,null,null,{"$f":"IF(Лист1!I38=\"\",\"\",Лист1!I38)","v":""},null,null,null,null,{"$f":"IF(Лист1!L38=\"\",\"\",Лист1!L38)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F39=\"\",\"\",Лист1!F39)","v":""},null,null,null,null,{"$f":"IF(Лист1!I39=\"\",\"\",Лист1!I39)","v":""},null,null,null,null,{"$f":"IF(Лист1!L39=\"\",\"\",Лист1!L39)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F40=\"\",\"\",Лист1!F40)","v":""},null,null,null,null,{"$f":"IF(Лист1!I40=\"\",\"\",Лист1!I40)","v":""},null,null,null,null,{"$f":"IF(Лист1!L40=\"\",\"\",Лист1!L40)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F41=\"\",\"\",Лист1!F41)","v":""},null,null,null,null,{"$f":"IF(Лист1!I41=\"\",\"\",Лист1!I41)","v":""},null,null,null,null,{"$f":"IF(Лист1!L41=\"\",\"\",Лист1!L41)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F42=\"\",\"\",Лист1!F42)","v":""},null,null,null,null,{"$f":"IF(Лист1!I42=\"\",\"\",Лист1!I42)","v":""},null,null,null,null,{"$f":"IF(Лист1!L42=\"\",\"\",Лист1!L42)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F43=\"\",\"\",Лист1!F43)","v":""},null,null,null,null,{"$f":"IF(Лист1!I43=\"\",\"\",Лист1!I43)","v":""},null,null,null,null,{"$f":"IF(Лист1!L43=\"\",\"\",Лист1!L43)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F44=\"\",\"\",Лист1!F44)","v":""},null,null,null,null,{"$f":"IF(Лист1!I44=\"\",\"\",Лист1!I44)","v":""},null,null,null,null,{"$f":"IF(Лист1!L44=\"\",\"\",Лист1!L44)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F45=\"\",\"\",Лист1!F45)","v":""},null,null,null,null,{"$f":"IF(Лист1!I45=\"\",\"\",Лист1!I45)","v":""},null,null,null,null,{"$f":"IF(Лист1!L45=\"\",\"\",Лист1!L45)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F46=\"\",\"\",Лист1!F46)","v":""},null,null,null,null,{"$f":"IF(Лист1!I46=\"\",\"\",Лист1!I46)","v":""},null,null,null,null,{"$f":"IF(Лист1!L46=\"\",\"\",Лист1!L46)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F47=\"\",\"\",Лист1!F47)","v":""},null,null,null,null,{"$f":"IF(Лист1!I47=\"\",\"\",Лист1!I47)","v":""},null,null,null,null,{"$f":"IF(Лист1!L47=\"\",\"\",Лист1!L47)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F48=\"\",\"\",Лист1!F48)","v":""},null,null,null,null,{"$f":"IF(Лист1!I48=\"\",\"\",Лист1!I48)","v":""},null,null,null,null,{"$f":"IF(Лист1!L48=\"\",\"\",Лист1!L48)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F49=\"\",\"\",Лист1!F49)","v":""},null,null,null,null,{"$f":"IF(Лист1!I49=\"\",\"\",Лист1!I49)","v":""},null,null,null,null,{"$f":"IF(Лист1!L49=\"\",\"\",Лист1!L49)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F50=\"\",\"\",Лист1!F50)","v":""},null,null,null,null,{"$f":"IF(Лист1!I50=\"\",\"\",Лист1!I50)","v":""},null,null,null,null,{"$f":"IF(Лист1!L50=\"\",\"\",Лист1!L50)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F51=\"\",\"\",Лист1!F51)","v":""},null,null,null,null,{"$f":"IF(Лист1!I51=\"\",\"\",Лист1!I51)","v":""},null,null,null,null,{"$f":"IF(Лист1!L51=\"\",\"\",Лист1!L51)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F52=\"\",\"\",Лист1!F52)","v":""},null,null,null,null,{"$f":"IF(Лист1!I52=\"\",\"\",Лист1!I52)","v":""},null,null,null,null,{"$f":"IF(Лист1!L52=\"\",\"\",Лист1!L52)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F53=\"\",\"\",Лист1!F53)","v":""},null,null,null,null,{"$f":"IF(Лист1!I53=\"\",\"\",Лист1!I53)","v":""},null,null,null,null,{"$f":"IF(Лист1!L53=\"\",\"\",Лист1!L53)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F54=\"\",\"\",Лист1!F54)","v":""},null,null,null,null,{"$f":"IF(Лист1!I54=\"\",\"\",Лист1!I54)","v":""},null,null,null,null,{"$f":"IF(Лист1!L54=\"\",\"\",Лист1!L54)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F55=\"\",\"\",Лист1!F55)","v":""},null,null,null,null,{"$f":"IF(Лист1!I55=\"\",\"\",Лист1!I55)","v":""},null,null,null,null,{"$f":"IF(Лист1!L55=\"\",\"\",Лист1!L55)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F56=\"\",\"\",Лист1!F56)","v":""},null,null,null,null,{"$f":"IF(Лист1!I56=\"\",\"\",Лист1!I56)","v":""},null,null,null,null,{"$f":"IF(Лист1!L56=\"\",\"\",Лист1!L56)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F57=\"\",\"\",Лист1!F57)","v":""},null,null,null,null,{"$f":"IF(Лист1!I57=\"\",\"\",Лист1!I57)","v":""},null,null,null,null,{"$f":"IF(Лист1!L57=\"\",\"\",Лист1!L57)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F58=\"\",\"\",Лист1!F58)","v":""},null,null,null,null,{"$f":"IF(Лист1!I58=\"\",\"\",Лист1!I58)","v":""},null,null,null,null,{"$f":"IF(Лист1!L58=\"\",\"\",Лист1!L58)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F59=\"\",\"\",Лист1!F59)","v":""},null,null,null,null,{"$f":"IF(Лист1!I59=\"\",\"\",Лист1!I59)","v":""},null,null,null,null,{"$f":"IF(Лист1!L59=\"\",\"\",Лист1!L59)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F60=\"\",\"\",Лист1!F60)","v":""},null,null,null,null,{"$f":"IF(Лист1!I60=\"\",\"\",Лист1!I60)","v":""},null,null,null,null,{"$f":"IF(Лист1!L60=\"\",\"\",Лист1!L60)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F61=\"\",\"\",Лист1!F61)","v":""},null,null,null,null,{"$f":"IF(Лист1!I61=\"\",\"\",Лист1!I61)","v":""},null,null,null,null,{"$f":"IF(Лист1!L61=\"\",\"\",Лист1!L61)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F62=\"\",\"\",Лист1!F62)","v":""},null,null,null,null,{"$f":"IF(Лист1!I62=\"\",\"\",Лист1!I62)","v":""},null,null,null,null,{"$f":"IF(Лист1!L62=\"\",\"\",Лист1!L62)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F63=\"\",\"\",Лист1!F63)","v":""},null,null,null,null,{"$f":"IF(Лист1!I63=\"\",\"\",Лист1!I63)","v":""},null,null,null,null,{"$f":"IF(Лист1!L63=\"\",\"\",Лист1!L63)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F64=\"\",\"\",Лист1!F64)","v":""},null,null,null,null,{"$f":"IF(Лист1!I64=\"\",\"\",Лист1!I64)","v":""},null,null,null,null,{"$f":"IF(Лист1!L64=\"\",\"\",Лист1!L64)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F65=\"\",\"\",Лист1!F65)","v":""},null,null,null,null,{"$f":"IF(Лист1!I65=\"\",\"\",Лист1!I65)","v":""},null,null,null,null,{"$f":"IF(Лист1!L65=\"\",\"\",Лист1!L65)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F66=\"\",\"\",Лист1!F66)","v":""},null,null,null,null,{"$f":"IF(Лист1!I66=\"\",\"\",Лист1!I66)","v":""},null,null,null,null,{"$f":"IF(Лист1!L66=\"\",\"\",Лист1!L66)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F67=\"\",\"\",Лист1!F67)","v":""},null,null,null,null,{"$f":"IF(Лист1!I67=\"\",\"\",Лист1!I67)","v":""},null,null,null,null,{"$f":"IF(Лист1!L67=\"\",\"\",Лист1!L67)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F68=\"\",\"\",Лист1!F68)","v":""},null,null,null,null,{"$f":"IF(Лист1!I68=\"\",\"\",Лист1!I68)","v":""},null,null,null,null,{"$f":"IF(Лист1!L68=\"\",\"\",Лист1!L68)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F69=\"\",\"\",Лист1!F69)","v":""},null,null,null,null,{"$f":"IF(Лист1!I69=\"\",\"\",Лист1!I69)","v":""},null,null,null,null,{"$f":"IF(Лист1!L69=\"\",\"\",Лист1!L69)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F70=\"\",\"\",Лист1!F70)","v":""},null,null,null,null,{"$f":"IF(Лист1!I70=\"\",\"\",Лист1!I70)","v":""},null,null,null,null,{"$f":"IF(Лист1!L70=\"\",\"\",Лист1!L70)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F71=\"\",\"\",Лист1!F71)","v":""},null,null,null,null,{"$f":"IF(Лист1!I71=\"\",\"\",Лист1!I71)","v":""},null,null,null,null,{"$f":"IF(Лист1!L71=\"\",\"\",Лист1!L71)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F72=\"\",\"\",Лист1!F72)","v":""},null,null,null,null,{"$f":"IF(Лист1!I72=\"\",\"\",Лист1!I72)","v":""},null,null,null,null,{"$f":"IF(Лист1!L72=\"\",\"\",Лист1!L72)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F73=\"\",\"\",Лист1!F73)","v":""},null,null,null,null,{"$f":"IF(Лист1!I73=\"\",\"\",Лист1!I73)","v":""},null,null,null,null,{"$f":"IF(Лист1!L73=\"\",\"\",Лист1!L73)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F74=\"\",\"\",Лист1!F74)","v":""},null,null,null,null,{"$f":"IF(Лист1!I74=\"\",\"\",Лист1!I74)","v":""},null,null,null,null,{"$f":"IF(Лист1!L74=\"\",\"\",Лист1!L74)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F75=\"\",\"\",Лист1!F75)","v":""},null,null,null,null,{"$f":"IF(Лист1!I75=\"\",\"\",Лист1!I75)","v":""},null,null,null,null,{"$f":"IF(Лист1!L75=\"\",\"\",Лист1!L75)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F76=\"\",\"\",Лист1!F76)","v":""},null,null,null,null,{"$f":"IF(Лист1!I76=\"\",\"\",Лист1!I76)","v":""},null,null,null,null,{"$f":"IF(Лист1!L76=\"\",\"\",Лист1!L76)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F77=\"\",\"\",Лист1!F77)","v":""},null,null,null,null,{"$f":"IF(Лист1!I77=\"\",\"\",Лист1!I77)","v":""},null,null,null,null,{"$f":"IF(Лист1!L77=\"\",\"\",Лист1!L77)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F78=\"\",\"\",Лист1!F78)","v":""},null,null,null,null,{"$f":"IF(Лист1!I78=\"\",\"\",Лист1!I78)","v":""},null,null,null,null,{"$f":"IF(Лист1!L78=\"\",\"\",Лист1!L78)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F79=\"\",\"\",Лист1!F79)","v":""},null,null,null,null,{"$f":"IF(Лист1!I79=\"\",\"\",Лист1!I79)","v":""},null,null,null,null,{"$f":"IF(Лист1!L79=\"\",\"\",Лист1!L79)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F80=\"\",\"\",Лист1!F80)","v":""},null,null,null,null,{"$f":"IF(Лист1!I80=\"\",\"\",Лист1!I80)","v":""},null,null,null,null,{"$f":"IF(Лист1!L80=\"\",\"\",Лист1!L80)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F81=\"\",\"\",Лист1!F81)","v":""},null,null,null,null,{"$f":"IF(Лист1!I81=\"\",\"\",Лист1!I81)","v":""},null,null,null,null,{"$f":"IF(Лист1!L81=\"\",\"\",Лист1!L81)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F82=\"\",\"\",Лист1!F82)","v":""},null,null,null,null,{"$f":"IF(Лист1!I82=\"\",\"\",Лист1!I82)","v":""},null,null,null,null,{"$f":"IF(Лист1!L82=\"\",\"\",Лист1!L82)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F83=\"\",\"\",Лист1!F83)","v":""},null,null,null,null,{"$f":"IF(Лист1!I83=\"\",\"\",Лист1!I83)","v":""},null,null,null,null,{"$f":"IF(Лист1!L83=\"\",\"\",Лист1!L83)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F84=\"\",\"\",Лист1!F84)","v":""},null,null,null,null,{"$f":"IF(Лист1!I84=\"\",\"\",Лист1!I84)","v":""},null,null,null,null,{"$f":"IF(Лист1!L84=\"\",\"\",Лист1!L84)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F85=\"\",\"\",Лист1!F85)","v":""},null,null,null,null,{"$f":"IF(Лист1!I85=\"\",\"\",Лист1!I85)","v":""},null,null,null,null,{"$f":"IF(Лист1!L85=\"\",\"\",Лист1!L85)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F86=\"\",\"\",Лист1!F86)","v":""},null,null,null,null,{"$f":"IF(Лист1!I86=\"\",\"\",Лист1!I86)","v":""},null,null,null,null,{"$f":"IF(Лист1!L86=\"\",\"\",Лист1!L86)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F87=\"\",\"\",Лист1!F87)","v":""},null,null,null,null,{"$f":"IF(Лист1!I87=\"\",\"\",Лист1!I87)","v":""},null,null,null,null,{"$f":"IF(Лист1!L87=\"\",\"\",Лист1!L87)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F88=\"\",\"\",Лист1!F88)","v":""},null,null,null,null,{"$f":"IF(Лист1!I88=\"\",\"\",Лист1!I88)","v":""},null,null,null,null,{"$f":"IF(Лист1!L88=\"\",\"\",Лист1!L88)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F89=\"\",\"\",Лист1!F89)","v":""},null,null,null,null,{"$f":"IF(Лист1!I89=\"\",\"\",Лист1!I89)","v":""},null,null,null,null,{"$f":"IF(Лист1!L89=\"\",\"\",Лист1!L89)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F90=\"\",\"\",Лист1!F90)","v":""},null,null,null,null,{"$f":"IF(Лист1!I90=\"\",\"\",Лист1!I90)","v":""},null,null,null,null,{"$f":"IF(Лист1!L90=\"\",\"\",Лист1!L90)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F91=\"\",\"\",Лист1!F91)","v":""},null,null,null,null,{"$f":"IF(Лист1!I91=\"\",\"\",Лист1!I91)","v":""},null,null,null,null,{"$f":"IF(Лист1!L91=\"\",\"\",Лист1!L91)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F92=\"\",\"\",Лист1!F92)","v":""},null,null,null,null,{"$f":"IF(Лист1!I92=\"\",\"\",Лист1!I92)","v":""},null,null,null,null,{"$f":"IF(Лист1!L92=\"\",\"\",Лист1!L92)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F93=\"\",\"\",Лист1!F93)","v":""},null,null,null,null,{"$f":"IF(Лист1!I93=\"\",\"\",Лист1!I93)","v":""},null,null,null,null,{"$f":"IF(Лист1!L93=\"\",\"\",Лист1!L93)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F94=\"\",\"\",Лист1!F94)","v":""},null,null,null,null,{"$f":"IF(Лист1!I94=\"\",\"\",Лист1!I94)","v":""},null,null,null,null,{"$f":"IF(Лист1!L94=\"\",\"\",Лист1!L94)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F95=\"\",\"\",Лист1!F95)","v":""},null,null,null,null,{"$f":"IF(Лист1!I95=\"\",\"\",Лист1!I95)","v":""},null,null,null,null,{"$f":"IF(Лист1!L95=\"\",\"\",Лист1!L95)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F96=\"\",\"\",Лист1!F96)","v":""},null,null,null,null,{"$f":"IF(Лист1!I96=\"\",\"\",Лист1!I96)","v":""},null,null,null,null,{"$f":"IF(Лист1!L96=\"\",\"\",Лист1!L96)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F97=\"\",\"\",Лист1!F97)","v":""},null,null,null,null,{"$f":"IF(Лист1!I97=\"\",\"\",Лист1!I97)","v":""},null,null,null,null,{"$f":"IF(Лист1!L97=\"\",\"\",Лист1!L97)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F98=\"\",\"\",Лист1!F98)","v":""},null,null,null,null,{"$f":"IF(Лист1!I98=\"\",\"\",Лист1!I98)","v":""},null,null,null,null,{"$f":"IF(Лист1!L98=\"\",\"\",Лист1!L98)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F99=\"\",\"\",Лист1!F99)","v":""},null,null,null,null,{"$f":"IF(Лист1!I99=\"\",\"\",Лист1!I99)","v":""},null,null,null,null,{"$f":"IF(Лист1!L99=\"\",\"\",Лист1!L99)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F100=\"\",\"\",Лист1!F100)","v":""},null,null,null,null,{"$f":"IF(Лист1!I100=\"\",\"\",Лист1!I100)","v":""},null,null,null,null,{"$f":"IF(Лист1!L100=\"\",\"\",Лист1!L100)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F101=\"\",\"\",Лист1!F101)","v":""},null,null,null,null,{"$f":"IF(Лист1!I101=\"\",\"\",Лист1!I101)","v":""},null,null,null,null,{"$f":"IF(Лист1!L101=\"\",\"\",Лист1!L101)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F102=\"\",\"\",Лист1!F102)","v":""},null,null,null,null,{"$f":"IF(Лист1!I102=\"\",\"\",Лист1!I102)","v":""},null,null,null,null,{"$f":"IF(Лист1!L102=\"\",\"\",Лист1!L102)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F103=\"\",\"\",Лист1!F103)","v":""},null,null,null,null,{"$f":"IF(Лист1!I103=\"\",\"\",Лист1!I103)","v":""},null,null,null,null,{"$f":"IF(Лист1!L103=\"\",\"\",Лист1!L103)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F104=\"\",\"\",Лист1!F104)","v":""},null,null,null,null,{"$f":"IF(Лист1!I104=\"\",\"\",Лист1!I104)","v":""},null,null,null,null,{"$f":"IF(Лист1!L104=\"\",\"\",Лист1!L104)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F105=\"\",\"\",Лист1!F105)","v":""},null,null,null,null,{"$f":"IF(Лист1!I105=\"\",\"\",Лист1!I105)","v":""},null,null,null,null,{"$f":"IF(Лист1!L105=\"\",\"\",Лист1!L105)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F106=\"\",\"\",Лист1!F106)","v":""},null,null,null,null,{"$f":"IF(Лист1!I106=\"\",\"\",Лист1!I106)","v":""},null,null,null,null,{"$f":"IF(Лист1!L106=\"\",\"\",Лист1!L106)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F107=\"\",\"\",Лист1!F107)","v":""},null,null,null,null,{"$f":"IF(Лист1!I107=\"\",\"\",Лист1!I107)","v":""},null,null,null,null,{"$f":"IF(Лист1!L107=\"\",\"\",Лист1!L107)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F108=\"\",\"\",Лист1!F108)","v":""},null,null,null,null,{"$f":"IF(Лист1!I108=\"\",\"\",Лист1!I108)","v":""},null,null,null,null,{"$f":"IF(Лист1!L108=\"\",\"\",Лист1!L108)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F109=\"\",\"\",Лист1!F109)","v":""},null,null,null,null,{"$f":"IF(Лист1!I109=\"\",\"\",Лист1!I109)","v":""},null,null,null,null,{"$f":"IF(Лист1!L109=\"\",\"\",Лист1!L109)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F110=\"\",\"\",Лист1!F110)","v":""},null,null,null,null,{"$f":"IF(Лист1!I110=\"\",\"\",Лист1!I110)","v":""},null,null,null,null,{"$f":"IF(Лист1!L110=\"\",\"\",Лист1!L110)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F111=\"\",\"\",Лист1!F111)","v":""},null,null,null,null,{"$f":"IF(Лист1!I111=\"\",\"\",Лист1!I111)","v":""},null,null,null,null,{"$f":"IF(Лист1!L111=\"\",\"\",Лист1!L111)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F112=\"\",\"\",Лист1!F112)","v":""},null,null,null,null,{"$f":"IF(Лист1!I112=\"\",\"\",Лист1!I112)","v":""},null,null,null,null,{"$f":"IF(Лист1!L112=\"\",\"\",Лист1!L112)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F113=\"\",\"\",Лист1!F113)","v":""},null,null,null,null,{"$f":"IF(Лист1!I113=\"\",\"\",Лист1!I113)","v":""},null,null,null,null,{"$f":"IF(Лист1!L113=\"\",\"\",Лист1!L113)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F114=\"\",\"\",Лист1!F114)","v":""},null,null,null,null,{"$f":"IF(Лист1!I114=\"\",\"\",Лист1!I114)","v":""},null,null,null,null,{"$f":"IF(Лист1!L114=\"\",\"\",Лист1!L114)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F115=\"\",\"\",Лист1!F115)","v":""},null,null,null,null,{"$f":"IF(Лист1!I115=\"\",\"\",Лист1!I115)","v":""},null,null,null,null,{"$f":"IF(Лист1!L115=\"\",\"\",Лист1!L115)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F116=\"\",\"\",Лист1!F116)","v":""},null,null,null,null,{"$f":"IF(Лист1!I116=\"\",\"\",Лист1!I116)","v":""},null,null,null,null,{"$f":"IF(Лист1!L116=\"\",\"\",Лист1!L116)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F117=\"\",\"\",Лист1!F117)","v":""},null,null,null,null,{"$f":"IF(Лист1!I117=\"\",\"\",Лист1!I117)","v":""},null,null,null,null,{"$f":"IF(Лист1!L117=\"\",\"\",Лист1!L117)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F118=\"\",\"\",Лист1!F118)","v":""},null,null,null,null,{"$f":"IF(Лист1!I118=\"\",\"\",Лист1!I118)","v":""},null,null,null,null,{"$f":"IF(Лист1!L118=\"\",\"\",Лист1!L118)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F119=\"\",\"\",Лист1!F119)","v":""},null,null,null,null,{"$f":"IF(Лист1!I119=\"\",\"\",Лист1!I119)","v":""},null,null,null,null,{"$f":"IF(Лист1!L119=\"\",\"\",Лист1!L119)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F120=\"\",\"\",Лист1!F120)","v":""},null,null,null,null,{"$f":"IF(Лист1!I120=\"\",\"\",Лист1!I120)","v":""},null,null,null,null,{"$f":"IF(Лист1!L120=\"\",\"\",Лист1!L120)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F121=\"\",\"\",Лист1!F121)","v":""},null,null,null,null,{"$f":"IF(Лист1!I121=\"\",\"\",Лист1!I121)","v":""},null,null,null,null,{"$f":"IF(Лист1!L121=\"\",\"\",Лист1!L121)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F122=\"\",\"\",Лист1!F122)","v":""},null,null,null,null,{"$f":"IF(Лист1!I122=\"\",\"\",Лист1!I122)","v":""},null,null,null,null,{"$f":"IF(Лист1!L122=\"\",\"\",Лист1!L122)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F123=\"\",\"\",Лист1!F123)","v":""},null,null,null,null,{"$f":"IF(Лист1!I123=\"\",\"\",Лист1!I123)","v":""},null,null,null,null,{"$f":"IF(Лист1!L123=\"\",\"\",Лист1!L123)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F124=\"\",\"\",Лист1!F124)","v":""},null,null,null,null,{"$f":"IF(Лист1!I124=\"\",\"\",Лист1!I124)","v":""},null,null,null,null,{"$f":"IF(Лист1!L124=\"\",\"\",Лист1!L124)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F125=\"\",\"\",Лист1!F125)","v":""},null,null,null,null,{"$f":"IF(Лист1!I125=\"\",\"\",Лист1!I125)","v":""},null,null,null,null,{"$f":"IF(Лист1!L125=\"\",\"\",Лист1!L125)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F126=\"\",\"\",Лист1!F126)","v":""},null,null,null,null,{"$f":"IF(Лист1!I126=\"\",\"\",Лист1!I126)","v":""},null,null,null,null,{"$f":"IF(Лист1!L126=\"\",\"\",Лист1!L126)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F127=\"\",\"\",Лист1!F127)","v":""},null,null,null,null,{"$f":"IF(Лист1!I127=\"\",\"\",Лист1!I127)","v":""},null,null,null,null,{"$f":"IF(Лист1!L127=\"\",\"\",Лист1!L127)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F128=\"\",\"\",Лист1!F128)","v":""},null,null,null,null,{"$f":"IF(Лист1!I128=\"\",\"\",Лист1!I128)","v":""},null,null,null,null,{"$f":"IF(Лист1!L128=\"\",\"\",Лист1!L128)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F129=\"\",\"\",Лист1!F129)","v":""},null,null,null,null,{"$f":"IF(Лист1!I129=\"\",\"\",Лист1!I129)","v":""},null,null,null,null,{"$f":"IF(Лист1!L129=\"\",\"\",Лист1!L129)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F130=\"\",\"\",Лист1!F130)","v":""},null,null,null,null,{"$f":"IF(Лист1!I130=\"\",\"\",Лист1!I130)","v":""},null,null,null,null,{"$f":"IF(Лист1!L130=\"\",\"\",Лист1!L130)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F131=\"\",\"\",Лист1!F131)","v":""},null,null,null,null,{"$f":"IF(Лист1!I131=\"\",\"\",Лист1!I131)","v":""},null,null,null,null,{"$f":"IF(Лист1!L131=\"\",\"\",Лист1!L131)","v":""}]
[null,null,null,null,null,null,null,{"$f":"IF(Лист1!F132=\"\",\"\",Лист1!F132)","v":""},null,null,null,null,{"$f":"IF(Лист1!I132=\"\",\"\",Лист1!I132)","v":""},null,null,null,null,{"$f":"IF(Лист1!L132=\"\",\"\",Лист1!L132)","v":""}]

{"sheet":"виды","index":2,"n_rows":7,"n_cols":1,"rows_kept":7,"cut":false,"hidden":false,"merged":[]}
["транспортный"]
["земельный"]
["имущественный"]
["имущественный-земельный"]
["транспортный-земельный"]
["транспортный-имущественный"]
["транспортный-земельный-имущественный"]